{"id":3433,"date":"2024-08-19T02:57:31","date_gmt":"2024-08-18T19:57:31","guid":{"rendered":"https:\/\/www.veladiamond.com\/?page_id=3433"},"modified":"2025-03-30T18:12:38","modified_gmt":"2025-03-30T11:12:38","slug":"alphabet","status":"publish","type":"page","link":"https:\/\/www.veladiamond.com\/en\/ring\/alphabet\/","title":{"rendered":"Alphabet"},"content":{"rendered":"\n\n\t<section class=\"section\" id=\"section_988714197\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\" style=\"max-width:1350px\" id=\"row-1265347824\">\n\n\t<div id=\"col-716326591\" class=\"col medium-4 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2400581053\" class=\"text line-height\">\n\t\t\n<h4><span style=\"font-size: 50%;\"><a href=\"https:\/\/www.veladiamond.com\/en\/\">Home<\/a> \/ <a href=\"https:\/\/www.veladiamond.com\/en\/ring\/\">All Ring<\/a> \/ Alphabet Initial diamond<\/span><\/h4>\n<h1 class=\"PDtext\" style=\"font-size: 170%;\">Ring<\/h1>\n<p>Alphabet Initial diamond<\/p>\n<hr \/>\n\t\t\n<style>\n#text-2400581053 {\n  font-size: 1.2rem;\n}\n@media (min-width:550px) {\n  #text-2400581053 {\n    font-size: 1.3rem;\n  }\n}\n@media (min-width:850px) {\n  #text-2400581053 {\n    font-size: 1.5rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2826446246\" class=\"text\">\n\t\t\n<h3 class=\"PDtext\">Shop by Style<\/h3>\n\t\t\n<style>\n#text-2826446246 {\n  color: #ce3375;\n}\n#text-2826446246 > * {\n  color: #ce3375;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row row-collapse\"  id=\"row-1273596012\">\n\n\t<div id=\"col-542723555\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"ux-menu stack stack-col justify-start ux-menu--divider-solid\">\n\t\t\n\t<div class=\"ux-menu-link flex menu-item\">\n\t\t<a class=\"ux-menu-link__link flex\" href=\"https:\/\/www.veladiamond.com\/en\/ring\/alphabet\/\" >\n\t\t\t\t\t\t<span class=\"ux-menu-link__text\">\n\t\t\t\tAlphabet Initial diamond\t\t\t<\/span>\n\t\t<\/a>\n\t<\/div>\n\t\n\t<div class=\"ux-menu-link flex menu-item\">\n\t\t<a class=\"ux-menu-link__link flex\" href=\"https:\/\/www.veladiamond.com\/en\/ring\/statement\/\" >\n\t\t\t\t\t\t<span class=\"ux-menu-link__text\">\n\t\t\t\tStatement\t\t\t<\/span>\n\t\t<\/a>\n\t<\/div>\n\t\n\t<div class=\"ux-menu-link flex menu-item\">\n\t\t<a class=\"ux-menu-link__link flex\" href=\"https:\/\/www.veladiamond.com\/en\/ring\/stackable\/\" >\n\t\t\t\t\t\t<span class=\"ux-menu-link__text\">\n\t\t\t\tStackable\t\t\t<\/span>\n\t\t<\/a>\n\t<\/div>\n\t\n\t<div class=\"ux-menu-link flex menu-item\">\n\t\t<a class=\"ux-menu-link__link flex\" href=\"https:\/\/www.veladiamond.com\/en\/ring\/minimalist\/\" >\n\t\t\t\t\t\t<span class=\"ux-menu-link__text\">\n\t\t\t\tMinimalist\t\t\t<\/span>\n\t\t<\/a>\n\t<\/div>\n\t\n\t<div class=\"ux-menu-link flex menu-item\">\n\t\t<a class=\"ux-menu-link__link flex\" href=\"https:\/\/www.veladiamond.com\/en\/ring\/professional\/\" >\n\t\t\t\t\t\t<span class=\"ux-menu-link__text\">\n\t\t\t\tProfessional\t\t\t<\/span>\n\t\t<\/a>\n\t<\/div>\n\t\n\t<div class=\"ux-menu-link flex menu-item\">\n\t\t<a class=\"ux-menu-link__link flex\" href=\"https:\/\/www.veladiamond.com\/en\/ring\/vl\/\" >\n\t\t\t\t\t\t<span class=\"ux-menu-link__text\">\n\t\t\t\tVL\t\t\t<\/span>\n\t\t<\/a>\n\t<\/div>\n\t\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-542723555 > .col-inner {\n  padding: 0px 0px 0px 20px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"text-1734247723\" class=\"text\">\n\t\t\n<h3 class=\"PDtext\">Filter<\/h3>\n\t\t\n<style>\n#text-1734247723 {\n  color: #ce3375;\n}\n#text-1734247723 > * {\n  color: #ce3375;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1375727841\" class=\"text hide-for-small\">\n\t\t\n\n\t\t\t<\/div>\n\t\n\t<div id=\"text-1894768723\" class=\"text show-for-small\">\n\t\t\n\n\t\t\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1013132619\" class=\"col medium-8 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"gap-26460626\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-26460626 {\n  padding-top: 10px;\n}\n@media (min-width:550px) {\n  #gap-26460626 {\n    padding-top: 30px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\n  \n    <div class=\"row large-columns-4 medium-columns-3 small-columns-2 row-small\" >\n  \n\t     <div class=\"product-small col has-hover product type-product post-5265 status-publish first instock product_cat-alphabet-initial-diamond-ring-en product_cat-all-shop-en product_cat-gifts-that-sparkle product_cat-ring-en has-post-thumbnail sale taxable shipping-taxable purchasable product-type-variable\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t<div class=\"product-small box \">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/www.veladiamond.com\/en\/product\/stylist-en-2\/gifts-that-sparkle\/custom-initial-diamond-ring\/\" aria-label=\"Custom Initial Diamond Ring\">\n\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.veladiamond.com\/wp-content\/uploads\/2024\/05\/Vela-ig-post-46-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Custom Initial Diamond Ring\" srcset=\"https:\/\/www.veladiamond.com\/wp-content\/uploads\/2024\/05\/Vela-ig-post-46-300x300.jpg 300w, https:\/\/www.veladiamond.com\/wp-content\/uploads\/2024\/05\/Vela-ig-post-46-150x150.jpg 150w, https:\/\/www.veladiamond.com\/wp-content\/uploads\/2024\/05\/Vela-ig-post-46-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.veladiamond.com\/wp-content\/uploads\/2024\/05\/Vela-ig-post-45-300x300.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"\" srcset=\"https:\/\/www.veladiamond.com\/wp-content\/uploads\/2024\/05\/Vela-ig-post-45-300x300.jpg 300w, https:\/\/www.veladiamond.com\/wp-content\/uploads\/2024\/05\/Vela-ig-post-45-150x150.jpg 150w, https:\/\/www.veladiamond.com\/wp-content\/uploads\/2024\/05\/Vela-ig-post-45-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t<div class=\"wishlist-icon\">\n\t\t\t<button class=\"wishlist-button button is-outline circle icon\" aria-label=\"Wishlist\">\n\t\t\t\t<i class=\"icon-heart\" ><\/i>\t\t\t<\/button>\n\t\t\t<div class=\"wishlist-popup dark\">\n\t\t\t\t\n<div\n\tclass=\"yith-wcwl-add-to-wishlist add-to-wishlist-5265 yith-wcwl-add-to-wishlist--link-style wishlist-fragment on-first-load\"\n\tdata-fragment-ref=\"5265\"\n\tdata-fragment-options=\"{&quot;base_url&quot;:&quot;&quot;,&quot;product_id&quot;:5265,&quot;parent_product_id&quot;:0,&quot;product_type&quot;:&quot;variable&quot;,&quot;is_single&quot;:false,&quot;in_default_wishlist&quot;:false,&quot;show_view&quot;:false,&quot;browse_wishlist_text&quot;:&quot;Browse wishlist&quot;,&quot;already_in_wishslist_text&quot;:&quot;The product is already in your wishlist!&quot;,&quot;product_added_text&quot;:&quot;Product added!&quot;,&quot;available_multi_wishlist&quot;:false,&quot;disable_wishlist&quot;:false,&quot;show_count&quot;:false,&quot;ajax_loading&quot;:false,&quot;loop_position&quot;:&quot;after_add_to_cart&quot;,&quot;item&quot;:&quot;add_to_wishlist&quot;}\"\n>\n\t\t\t\n\t\t\t<!-- ADD TO WISHLIST -->\n\t\t\t\n<div class=\"yith-wcwl-add-button\">\n\t\t<a\n\t\thref=\"?add_to_wishlist=5265&#038;_wpnonce=2ec34bbdcc\"\n\t\tclass=\"add_to_wishlist single_add_to_wishlist\"\n\t\tdata-product-id=\"5265\"\n\t\tdata-product-type=\"variable\"\n\t\tdata-original-product-id=\"0\"\n\t\tdata-title=\"Add to wishlist\"\n\t\trel=\"nofollow\"\n\t>\n\t\t<svg id=\"yith-wcwl-icon-heart-outline\" class=\"yith-wcwl-icon-svg\" fill=\"none\" stroke-width=\"1.5\" stroke=\"currentColor\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n  <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"M21 8.25c0-2.485-2.099-4.5-4.688-4.5-1.935 0-3.597 1.126-4.312 2.733-.715-1.607-2.377-2.733-4.313-2.733C5.1 3.75 3 5.765 3 8.25c0 7.22 9 12 9 12s9-4.78 9-12Z\"><\/path>\n<\/svg>\t\t<span>Add to wishlist<\/span>\n\t<\/a>\n<\/div>\n\n\t\t\t<!-- COUNT TEXT -->\n\t\t\t\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t<a href=\"https:\/\/www.veladiamond.com\/en\/product\/stylist-en-2\/gifts-that-sparkle\/custom-initial-diamond-ring\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5265\" data-quantity=\"1\" class=\"add-to-cart-grid no-padding is-transparent product_type_variable add_to_cart_button cfvsw_ajax_add_to_cart\" data-product_id=\"5265\" data-product_sku=\"Custom-ring\" aria-label=\"Select options for &ldquo;Custom Initial Diamond Ring&rdquo;\" rel=\"nofollow\" data-add_to_cart_text=\"Add to Cart\" data-select_options_text=\"Select options\"><div class=\"cart-icon tooltip is-small\" title=\"Select options\"><strong>+<\/strong><\/div><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5265\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n  <a class=\"quick-view\" data-prod=\"5265\" href=\"#quick-view\">Quick View<\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text box-text-products\">\n\t\t\t<div class=\"title-wrapper\"><p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.veladiamond.com\/en\/product\/stylist-en-2\/gifts-that-sparkle\/custom-initial-diamond-ring\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Custom Initial Diamond Ring<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>181,700&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#3647;<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Original price was: 181,700&nbsp;&#3647;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>79,000&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#3647;<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Current price is: 79,000&nbsp;&#3647;.<\/span><\/span>\n<\/div>\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\n<\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_988714197 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":3237,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3433","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alphabet - veladiamond<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alphabet - veladiamond\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.veladiamond.com\/en\/ring\/alphabet\/\" \/>\n<meta property=\"og:site_name\" content=\"veladiamond\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-30T11:12:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.veladiamond.com\\\/en\\\/ring\\\/alphabet\\\/\",\"url\":\"https:\\\/\\\/www.veladiamond.com\\\/en\\\/ring\\\/alphabet\\\/\",\"name\":\"Alphabet - veladiamond\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.veladiamond.com\\\/#website\"},\"datePublished\":\"2024-08-18T19:57:31+00:00\",\"dateModified\":\"2025-03-30T11:12:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.veladiamond.com\\\/en\\\/ring\\\/alphabet\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.veladiamond.com\\\/en\\\/ring\\\/alphabet\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.veladiamond.com\\\/en\\\/ring\\\/alphabet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.veladiamond.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ring\",\"item\":\"https:\\\/\\\/www.veladiamond.com\\\/en\\\/ring\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alphabet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.veladiamond.com\\\/#website\",\"url\":\"https:\\\/\\\/www.veladiamond.com\\\/\",\"name\":\"veladiamond\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.veladiamond.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alphabet - veladiamond","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Alphabet - veladiamond","og_url":"https:\/\/www.veladiamond.com\/en\/ring\/alphabet\/","og_site_name":"veladiamond","article_modified_time":"2025-03-30T11:12:38+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.veladiamond.com\/en\/ring\/alphabet\/","url":"https:\/\/www.veladiamond.com\/en\/ring\/alphabet\/","name":"Alphabet - veladiamond","isPartOf":{"@id":"https:\/\/www.veladiamond.com\/#website"},"datePublished":"2024-08-18T19:57:31+00:00","dateModified":"2025-03-30T11:12:38+00:00","breadcrumb":{"@id":"https:\/\/www.veladiamond.com\/en\/ring\/alphabet\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.veladiamond.com\/en\/ring\/alphabet\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.veladiamond.com\/en\/ring\/alphabet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.veladiamond.com\/en\/"},{"@type":"ListItem","position":2,"name":"Ring","item":"https:\/\/www.veladiamond.com\/en\/ring\/"},{"@type":"ListItem","position":3,"name":"Alphabet"}]},{"@type":"WebSite","@id":"https:\/\/www.veladiamond.com\/#website","url":"https:\/\/www.veladiamond.com\/","name":"veladiamond","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.veladiamond.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.veladiamond.com\/en\/wp-json\/wp\/v2\/pages\/3433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.veladiamond.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.veladiamond.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.veladiamond.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.veladiamond.com\/en\/wp-json\/wp\/v2\/comments?post=3433"}],"version-history":[{"count":5,"href":"https:\/\/www.veladiamond.com\/en\/wp-json\/wp\/v2\/pages\/3433\/revisions"}],"predecessor-version":[{"id":3480,"href":"https:\/\/www.veladiamond.com\/en\/wp-json\/wp\/v2\/pages\/3433\/revisions\/3480"}],"up":[{"embeddable":true,"href":"https:\/\/www.veladiamond.com\/en\/wp-json\/wp\/v2\/pages\/3237"}],"wp:attachment":[{"href":"https:\/\/www.veladiamond.com\/en\/wp-json\/wp\/v2\/media?parent=3433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}